{"id":9478,"count":1,"description":"","link":"\/blog\/tag\/ghd-helios-professional-hairdryer\/","name":"Ghd Helios Professional Hairdryer","slug":"ghd-helios-professional-hairdryer","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"\/blog\/wp-json\/wp\/v2\/tags\/9478"}],"collection":[{"href":"\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"\/blog\/wp-json\/wp\/v2\/posts?tags=9478"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}